{"id":110650,"date":"2024-06-14T09:19:28","date_gmt":"2024-06-14T09:19:28","guid":{"rendered":"https:\/\/www.gedy.com\/?p=110650"},"modified":"2024-06-17T09:38:39","modified_gmt":"2024-06-17T09:38:39","slug":"wichtige-mitteilung-bezueglich-einer-verletzung-des-schutze-personenbezogener-daten","status":"publish","type":"post","link":"https:\/\/www.gedy.com\/de\/wichtige-mitteilung-bezueglich-einer-verletzung-des-schutze-personenbezogener-daten\/","title":{"rendered":"Wichtige Mitteilung bez\u00fcglich einer Verletzung des Schutze personenbezogener Daten"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"110650\" class=\"elementor elementor-110650 elementor-110579\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a73762a e-flex e-con-boxed e-con e-parent\" data-id=\"7a73762a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67fe700c elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"67fe700c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Wichtige Mitteilung bez\u00fcglich einer Verletzung des Schutze personenbezogener Daten<span style=\"color:red\">.<\/span><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-224e3f1c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"224e3f1c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-97c47b0\" data-id=\"97c47b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-320fda32 elementor-widget elementor-widget-text-editor\" data-id=\"320fda32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p3\"><em><b>Mitteilung an die Betroffenen gem\u00e4\u00df Artikel 34 der EU-Verordnung 2016\/679 <\/b><\/em><\/p><p class=\"p3\">Wir informieren Sie hiermit gem\u00e4\u00df Artikel 34 der EU-Verordnung 2016\/679, dass unser Unternehmen einem Cyberangriff (<em>Ransomware<\/em>) ausgesetzt war, der die Server des Unternehmens betroffen hat und m\u00f6glicherweise zu einer Verletzung der darin enthaltenen personenbezogenen Daten gef\u00fchrt hat.<\/p><p class=\"p3\">Die durchgef\u00fchrten Untersuchungen haben ergeben, dass die Verletzung personenbezogener Daten am 23.04.2024 aufgetreten sein k\u00f6nnte und sich am Sonntag, den 05.05.2024, manifestierte, da der Zugriff auf die IT-Systeme des Unternehmens am Montag, den 06.05.2024, verhindert wurde.<\/p><p class=\"p3\">Die beschriebene Verletzung wurde unverz\u00fcglich der Aufsichtsbeh\u00f6rde (sogenannte Datenschutzbeh\u00f6rde) am 8. Mai 2024 gemeldet und den zust\u00e4ndigen Beh\u00f6rden am 14. Mai 2024 angezeigt.<\/p><p class=\"p3\">Die Angreifer hatten m\u00f6glicherweise Zugriff auf personenbezogene Daten, die auf den betroffenen Servern gespeichert sind. Es war jedoch nicht m\u00f6glich festzustellen, ob tats\u00e4chlich eine Datenexfiltration stattgefunden hat.<\/p><p class=\"p3\">Sobald wir die Verletzung festgestellt haben, haben wir unverz\u00fcglich eine spezialisierte IT-Firma beauftragt, den Angriff zu analysieren und seine Auswirkungen zu mindern. Diese Firma hat dann das IT-System des Unternehmens in k\u00fcrzester Zeit wiederhergestellt, indem sie ein neues sicheres IT-Netzwerk geschaffen hat, in das schrittweise alle Daten aus dem letzten <em>Backup<\/em> vom 03.05.2024 geladen wurden; dies erm\u00f6glichte uns, die Verf\u00fcgbarkeit der Daten vollst\u00e4ndig wiederherzustellen. Bis heute sind weitere Untersuchungen durch die beauftragte IT-Firma noch im Gange.<\/p><p class=\"p3\">Um zu verhindern, dass solche Vorf\u00e4lle in Zukunft erneut auftreten, pr\u00fcfen wir zusammen mit der IT-Firma neue Sicherheitsma\u00dfnahmen, die geeignet sind, die verwendeten Schutzsysteme zu verbessern.<\/p><p class=\"p3\">Wir empfehlen Ihnen, besondere Aufmerksamkeit auf <em>E-Mails,<\/em> SMS, Nachrichten oder Telefonanrufe zu richten, in denen pers\u00f6nliche Daten angefordert werden, und die Glaubw\u00fcrdigkeit des Anfragenden sorgf\u00e4ltig zu pr\u00fcfen. Seien Sie vorsichtig bei <em>E-Mails<\/em>, SMS und anderen Nachrichtenquellen, die verd\u00e4chtige oder ungew\u00f6hnliche Hyperlinks (<em>Links<\/em>) oder Anh\u00e4nge enthalten.<\/p><p class=\"p3\">Mit freundlichen Gr\u00fc\u00dfen,<\/p><p class=\"p3\">Gedy S.p.a.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Mitteilung an die Betroffenen gem\u00e4\u00df Artikel 34 der EU-Verordnung 2016\/679 Wir informieren Sie hiermit gem\u00e4\u00df Artikel 34 der EU-Verordnung 2016\/679, dass unser Unternehmen einem Cyberangriff (Ransomware) ausgesetzt war, der die Server des Unternehmens betroffen hat und m\u00f6glicherweise zu einer Verletzung der darin enthaltenen personenbezogenen Daten gef\u00fchrt hat. Die durchgef\u00fchrten Untersuchungen haben ergeben, dass die Verletzung [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":111783,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[10199],"tags":[10182],"class_list":["post-110650","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-stampa-de","tag-news-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.gedy.com\/de\/wp-json\/wp\/v2\/posts\/110650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gedy.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gedy.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gedy.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gedy.com\/de\/wp-json\/wp\/v2\/comments?post=110650"}],"version-history":[{"count":15,"href":"https:\/\/www.gedy.com\/de\/wp-json\/wp\/v2\/posts\/110650\/revisions"}],"predecessor-version":[{"id":110698,"href":"https:\/\/www.gedy.com\/de\/wp-json\/wp\/v2\/posts\/110650\/revisions\/110698"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gedy.com\/de\/wp-json\/wp\/v2\/media\/111783"}],"wp:attachment":[{"href":"https:\/\/www.gedy.com\/de\/wp-json\/wp\/v2\/media?parent=110650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gedy.com\/de\/wp-json\/wp\/v2\/categories?post=110650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gedy.com\/de\/wp-json\/wp\/v2\/tags?post=110650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}